{"id":768,"date":"2026-01-08T19:08:07","date_gmt":"2026-01-08T19:08:07","guid":{"rendered":"https:\/\/idosmarketing.com\/?page_id=768"},"modified":"2026-03-03T03:10:21","modified_gmt":"2026-03-03T03:10:21","slug":"contacto","status":"publish","type":"page","link":"https:\/\/idosmarketing.com\/en\/contacto\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"768\" class=\"elementor elementor-768\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29e6c4d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"29e6c4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3d4a7f6a\" data-id=\"3d4a7f6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e21f4d4 elementor-widget elementor-widget-image\" data-id=\"e21f4d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/idosmarketing.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"697\" height=\"219\" src=\"https:\/\/idosmarketing.com\/wp-content\/uploads\/2026\/01\/Logo-web.png\" class=\"attachment-large size-large wp-image-371\" alt=\"\" srcset=\"https:\/\/idosmarketing.com\/wp-content\/uploads\/2026\/01\/Logo-web.png 697w, https:\/\/idosmarketing.com\/wp-content\/uploads\/2026\/01\/Logo-web-300x94.png 300w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e4d012b elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-tablet_extra elementor-hidden-mobile_extra\" data-id=\"e4d012b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-278ed84c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"278ed84c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-233822eb\" data-id=\"233822eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c580776 elementor-widget__width-auto elementor-widget elementor-widget-elementskit-header-search\" data-id=\"c580776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-header-search.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <a href=\"#ekit_modal-popup-c580776\" class=\"ekit_navsearch-button ekit-modal-popup\" aria-label=\"navsearch-button\">\n            <i aria-hidden=\"true\" class=\"icon icon-search11\"><\/i>        <\/a>\n        <!-- language switcher strart -->\n        <!-- xs modal -->\n        <div class=\"zoom-anim-dialog mfp-hide ekit_modal-searchPanel\" id=\"ekit_modal-popup-c580776\">\n            <div class=\"ekit-search-panel\">\n            <!-- Polylang search - thanks to Alain Melsens -->\n                <form role=\"search\" method=\"get\" class=\"ekit-search-group\" action=\"https:\/\/idosmarketing.com\/\">\n                    <input type=\"search\" class=\"ekit_search-field\" aria-label=\"search-form\" placeholder=\"Search...\" value=\"\" name=\"s\">\n\t\t\t\t\t<button type=\"submit\" class=\"ekit_search-button\" aria-label=\"search-button\">\n                        <i aria-hidden=\"true\" class=\"icon icon-search11\"><\/i>                    <\/button>\n                <\/form>\n            <\/div>\n        <\/div><!-- End xs modal -->\n        <!-- end language switcher strart -->\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c0520cd\" data-id=\"6c0520cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c390213 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"5c390213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-2e5b662\" href=\"https:\/\/www.instagram.com\/idosmarketing\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-5b2d06a\" href=\"https:\/\/www.facebook.com\/profile.php?id=61581277973702\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-7a44103\" href=\"https:\/\/www.linkedin.com\/company\/96017041\/admin\/dashboard\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-fe76e9a\" href=\"https:\/\/www.youtube.com\/channel\/UCkstu7unVrYmTWHP9SQd5AA\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5458f6c7\" data-id=\"5458f6c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ee8a50a elementor-widget__width-auto elementor-widget elementor-widget-tf-nav-menu\" data-id=\"2ee8a50a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tf-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tf-nav-menu tf-alignment-left horizontal menu-panel-style-left tf_link_effect_underline tf_animation_line_fade dropdown-style1 tf-nav-6a581381847cc\" data-id_random=\"tf-nav-6a581381847cc\">\r\n\t\t\t\t<div class=\"nav-panel mobile-menu-alignment-left\">\r\n\t\t\t\t\t<div class=\"wrap-logo-nav\"><a href=\"https:\/\/idosmarketing.com\/en\/\" class=\"logo-nav\"><img decoding=\"async\" src=\"https:\/\/idosmarketing.com\/wp-content\/uploads\/2026\/01\/Logo-web.png\" alt=\"i2 Marketing\"><\/a><\/div>\r\n\t\t\t\t\t<div class=\"mainnav-mobi\"><div class=\"menu-container tf-menu-container\"><ul id=\"menu-principal\" class=\"menu\"><li id=\"menu-item-273\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-273\"><a href=\"https:\/\/idosmarketing.com\">Inicio<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-335\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-335\"><a href=\"https:\/\/idosmarketing.com\/en\/nosotros\/\">Nosotros<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-443\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-443\"><a href=\"#\">Portafolio<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-442\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-442\"><a href=\"https:\/\/idosmarketing.com\/en\/agencia-de-comunicaciones\/\">Agencia de Comunicaciones<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n\t<li id=\"menu-item-441\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-441\"><a href=\"https:\/\/idosmarketing.com\/en\/btl-cliente-externo-e-interno\/\">BTL: Cliente externo e interno<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n\t<li id=\"menu-item-438\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-438\"><a href=\"https:\/\/idosmarketing.com\/en\/consultores-sector-automotor\/\">Consultores Sector Automotor<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-494\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-494\"><a href=\"https:\/\/idosmarketing.com\/en\/clientes\/\">Clientes<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-773\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-773\"><a href=\"https:\/\/idosmarketing.com\/en\/contacto\/\">Contacto<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<\/ul><\/div><\/div>\r\n\t\t\t\t\t<div class=\"wrap-close-menu-panel-style-default\">\r\n\t\t\t\t\t\t<button class=\"close-menu-panel-style-default\"><i class=\"fas fa-times\"><\/i><\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"mainnav nav\"><div class=\"menu-container tf-menu-container\"><ul id=\"menu-principal\" class=\"menu\"><li id=\"menu-item-273\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-273\"><a href=\"https:\/\/idosmarketing.com\">Inicio<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-335\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-335\"><a href=\"https:\/\/idosmarketing.com\/en\/nosotros\/\">Nosotros<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-443\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-443\"><a href=\"#\">Portafolio<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-442\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-442\"><a href=\"https:\/\/idosmarketing.com\/en\/agencia-de-comunicaciones\/\">Agencia de Comunicaciones<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n\t<li id=\"menu-item-441\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-441\"><a href=\"https:\/\/idosmarketing.com\/en\/btl-cliente-externo-e-interno\/\">BTL: Cliente externo e interno<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n\t<li id=\"menu-item-438\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-438\"><a href=\"https:\/\/idosmarketing.com\/en\/consultores-sector-automotor\/\">Consultores Sector Automotor<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-494\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-494\"><a href=\"https:\/\/idosmarketing.com\/en\/clientes\/\">Clientes<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<li id=\"menu-item-773\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-773\"><a href=\"https:\/\/idosmarketing.com\/en\/contacto\/\">Contacto<i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/a><\/li>\n<\/ul><\/div><\/div>\r\n\t\t\t\t<div class=\"mobile-menu-overlay\"><\/div>\r\n\t\t\t\t<button class=\"tf-close\"><i class=\"fas fa-times\"><\/i><\/button>\r\n\t\t\t\t<button class=\"btn-menu-mobile\"><span class=\"open-icon\"><i class=\"fas fa-bars\"><\/i><\/span><\/button>\r\n\t\t\t\t<button class=\"btn-menu-only\"><span class=\"open-icon\"><i class=\"fas fa-bars\"><\/i><\/span><\/button>\r\n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f6d48db elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra\" data-id=\"f6d48db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e2e385c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e2e385c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49586729\" data-id=\"49586729\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64dc6f82 elementor-widget-laptop__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"64dc6f82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19737d14\" data-id=\"19737d14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed2064b elementor-widget elementor-widget-heading\" data-id=\"ed2064b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+573102155694\">+57 310 215 5694<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c1061a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c1061a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35b89a3f\" data-id=\"35b89a3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1be35c0b elementor-widget elementor-widget-heading\" data-id=\"1be35c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cons\u00faltanos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2965676f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2965676f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fa398e3\" data-id=\"1fa398e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0701f9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6d0701f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cont\u00e1ctenos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eae1ef4 elementor-widget elementor-widget-heading\" data-id=\"3eae1ef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00a1Hablemos de c\u00f3mo transformar tus ideas en grandes experiencias!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b0d78b7 elementor-widget elementor-widget-text-editor\" data-id=\"6b0d78b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En <strong>i2 Marketing<\/strong>, creemos que cada conexi\u00f3n tiene el poder de trascender. Ya sea que necesites una agencia de comunicaciones estrat\u00e9gica, eventos memorables de cualquier magnitud, campa\u00f1as BTL impactantes, relaciones p\u00fablicas que amplifiquen tu mensaje, o capacitaciones especializadas en el sector automotor, estamos listos para ser tu aliado.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d8c8b66\" data-id=\"4d8c8b66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-898bc25 elementor-widget elementor-widget-text-editor\" data-id=\"898bc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Completa el formulario y d\u00e9janos ayudarte a construir historias que conecten, sorprendan e inspiren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-027f3ae elementor-widget elementor-widget-formidable\" data-id=\"027f3ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"formidable.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"frm_forms  with_frm_style frm_style_estilo-de-formidable\" id=\"frm_form_1_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form \" id=\"form_contact-form\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Cont\u00e1ctenos<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"1\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_1\" id=\"frm_hide_fields_1\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_1\" name=\"frm_submit_entry_1\" value=\"1befbe8640\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/768\" \/><div id=\"frm_field_1_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n\t<label for=\"field_qh4icy\" id=\"field_qh4icy_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu nombre?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_qh4icy\" name=\"item_meta[1]\" value=\"\"  data-reqmsg=\"\u00bfCu\u00e1l es tu nombre? no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu nombre? no es v\u00e1lido\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_10_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\n\t<label for=\"field_5paj5\" id=\"field_5paj5_label\" class=\"frm_primary_label\">Empresa d\u00f3nde trabajas\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\n\t<\/label>\n\t<input type=\"text\" id=\"field_5paj5\" name=\"item_meta[10]\" value=\"\"  data-reqmsg=\"Empresa d\u00f3nde trabajas no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Empresa d\u00f3nde trabajas no es v\u00e1lido\" aria-invalid=\"false\"  \/>\n\t\n\t\n<\/div>\n<div id=\"frm_field_3_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n\t<label for=\"field_29yf4d\" id=\"field_29yf4d_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu correo electr\u00f3nico?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"email\" id=\"field_29yf4d\" name=\"item_meta[3]\" value=\"\"  data-reqmsg=\"\u00bfCu\u00e1l es tu correo electr\u00f3nico? no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Please enter a valid email address\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_7_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n\t<label for=\"field_qrcbn\" id=\"field_qrcbn_label\" class=\"frm_primary_label\">Celular \r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"tel\" id=\"field_qrcbn\" name=\"item_meta[7]\" value=\"\"  data-reqmsg=\"Celular  no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Celular  no es v\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_9_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first vertical_radio\">\r\n\t<div  id=\"field_rqdq9_label\" class=\"frm_primary_label\">\u00bfC\u00f3mo prefieres que te contactemos?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/div>\r\n\t<div class=\"frm_opt_container\" aria-labelledby=\"field_rqdq9_label\" role=\"radiogroup\" aria-required=\"true\">\t\t<div class=\"frm_radio\" id=\"frm_radio_9-0\">\t\t\t<label  for=\"field_rqdq9-0\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[9]\" id=\"field_rqdq9-0\" value=\"Llamada telef\u00f3nica\"\n\t\t data-reqmsg=\"\u00bfC\u00f3mo prefieres que te contactemos? no puede estar en blanco.\" data-invmsg=\"\u00bfC\u00f3mo prefieres que te contactemos? no es v\u00e1lido\"   \/> Llamada telef\u00f3nica<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_9-1\">\t\t\t<label  for=\"field_rqdq9-1\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[9]\" id=\"field_rqdq9-1\" value=\"Correo electr\u00f3nico\"\n\t\t data-reqmsg=\"\u00bfC\u00f3mo prefieres que te contactemos? no puede estar en blanco.\" data-invmsg=\"\u00bfC\u00f3mo prefieres que te contactemos? no es v\u00e1lido\"   \/> Correo electr\u00f3nico<\/label><\/div>\n<\/div>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_6_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit frm_flex\">\r\n<button class=\"frm_button_submit\" type=\"submit\"  >Enviar<\/button>\r\n\r\n\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_11_container\">\n\t\t\t<label for=\"field_uht6p\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_uht6p\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[11]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"OoKMvSin\/QftIg8tlYd6qgHkZ1Wd7xmhExsiF+Ev33A=\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9ed3271 e-flex e-con-boxed e-con e-parent\" data-id=\"9ed3271\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7732cb9 e-con-full e-flex e-con e-child\" data-id=\"7732cb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-629d1b0 e-con-full e-flex e-con e-child\" data-id=\"629d1b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91656bb elementor-widget elementor-widget-heading\" data-id=\"91656bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00a1En breve nos pondremos en contacto contigo para empezar a crear algo incre\u00edble juntos!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01b7f44 e-con-full e-flex e-con e-child\" data-id=\"01b7f44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92902da e-flex e-con-boxed e-con e-parent\" data-id=\"92902da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c063c9 e-con-full e-flex e-con e-child\" data-id=\"4c063c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8eed8ab elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"8eed8ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-smartphone\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t+57 310 215 5694\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6777477 e-con-full e-flex e-con e-child\" data-id=\"6777477\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab9402 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"0ab9402\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-mail\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tcarias@idosmarketing.com\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5384ff e-con-full e-flex e-con e-child\" data-id=\"d5384ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-086b48e elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"086b48e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-map-marker1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCra 14 # 93b - 29,\u00a0Bogot\u00e1\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3280d16 e-con-full e-flex e-con e-parent\" data-id=\"3280d16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40c4db5 elementor-widget elementor-widget-html\" data-id=\"40c4db5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3976.5236860711084!2d-74.0527958893035!3d4.67864329527666!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x8e3f9a93ab58cf61%3A0x2eb622adbede722e!2sCra.%2014%20%2393B%20-%2029%2C%20Bogot%C3%A1!5e0!3m2!1ses-419!2sco!4v1767899546178!5m2!1ses-419!2sco\" width=\"600\" height=\"500\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ef4685a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ef4685a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4a042341\" data-id=\"4a042341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a89395b elementor-widget elementor-widget-image\" data-id=\"7a89395b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"863\" height=\"1024\" src=\"https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-863x1024.png\" class=\"attachment-large size-large wp-image-247\" alt=\"\" srcset=\"https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-863x1024.png 863w, https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-253x300.png 253w, https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-768x911.png 768w, https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-1294x1536.png 1294w, https:\/\/idosmarketing.com\/wp-content\/uploads\/2025\/12\/imagotipo-blanco-i2-1-1726x2048.png 1726w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4f755275\" data-id=\"4f755275\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dc11381 elementor-widget elementor-widget-heading\" data-id=\"1dc11381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">i2 Marketing<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cdbafec elementor-widget elementor-widget-text-editor\" data-id=\"3cdbafec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Integramos estrategia, creatividad y ejecuci\u00f3n para construir marcas que conectan y dejan huella.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1970c140\" data-id=\"1970c140\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-781e356e elementor-widget elementor-widget-heading\" data-id=\"781e356e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Men\u00fa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39edfb59 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"39edfb59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.idosmarketing.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/idosmarketing.com\/nosotros\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nosotros<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/idosmarketing.com\/agencia-de-comunicaciones\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Portafolio<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/idosmarketing.com\/clientes\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Clientes<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/idosmarketing.com\/contacto\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contacto<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-16e8cbc9\" data-id=\"16e8cbc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e43eee elementor-widget elementor-widget-heading\" data-id=\"36e43eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos encuentran<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2463e234 elementor-widget elementor-widget-heading\" data-id=\"2463e234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">+57 310 215 5694\n+571 6225916<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e2e78b elementor-widget elementor-widget-heading\" data-id=\"68e2e78b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">carias@idosmarketing.com<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49161123 elementor-widget elementor-widget-text-editor\" data-id=\"49161123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cra 14 # 93b &#8211; 29,\u00a0Bogot\u00e1<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-45dfab9f e-flex e-con-boxed e-con e-parent\" data-id=\"45dfab9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-41c3dc56 e-con-full e-flex e-con e-child\" data-id=\"41c3dc56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9a49f3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f9a49f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.instagram.com\/idosmarketing\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-instagram-1\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">@idosmarketing<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32ac233c e-con-full e-flex e-con e-child\" data-id=\"32ac233c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-114a523b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"114a523b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.facebook.com\/profile.php?id=61581277973702\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">i2 Marketing<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab12eef e-con-full e-flex e-con e-child\" data-id=\"ab12eef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72cf444f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"72cf444f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/company\/idosmarketing\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">idosmarketing<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ed9441e e-con-full e-flex e-con e-child\" data-id=\"4ed9441e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca22ed1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2ca22ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.youtube.com\/channel\/UCkstu7unVrYmTWHP9SQd5AA\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">@I2Marketingcol<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ed3a94d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ed3a94d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-399af1f7\" data-id=\"399af1f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77c0dffb elementor-widget elementor-widget-elementskit-heading\" data-id=\"77c0dffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><a href=\"#\"><p class=\"ekit-heading--title elementskit-section-title \"> \u00a9 Copyright i2 Marketing - 2026 <\/p><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Instagram Facebook Linkedin Youtube Inicio Nosotros Portafolio Agencia de Comunicaciones BTL: Cliente externo e interno Consultores Sector Automotor Clientes Contacto Inicio Nosotros Portafolio Agencia de Comunicaciones BTL: Cliente externo e interno Consultores Sector Automotor Clientes Contacto +57 310 215 5694 Cons\u00faltanos Cont\u00e1ctenos \u00a1Hablemos de c\u00f3mo transformar tus ideas en grandes experiencias! En i2 Marketing, creemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-768","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/pages\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":55,"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/pages\/768\/revisions"}],"predecessor-version":[{"id":1500,"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/pages\/768\/revisions\/1500"}],"wp:attachment":[{"href":"https:\/\/idosmarketing.com\/en\/wp-json\/wp\/v2\/media?parent=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}